{"id":3838,"count":1,"description":"","link":"https:\/\/losangeleschinesenews.com\/index.php\/tag\/%e4%ba%bf%e7%94%b3%e8%af%b7%e4%bf%a1%e8%b4%b7%e7%9a%84%e4%ba%ba%e5%8f%97%e5%88%b0%e5%bd%b1%e5%93%8d%e9%bb%91%e5%ae%a2%e8%8e%b7%e5%be%97%e4%ba%86%e4%bf%a1%e7%94%a8%e8%af%84%e5%88%86%e4%bd%99%e9%a2%9d\/","name":"\u4ebf\u7533\u8bf7\u4fe1\u8d37\u7684\u4eba\u53d7\u5230\u5f71\u54cd\u9ed1\u5ba2\u83b7\u5f97\u4e86\u4fe1\u7528\u8bc4\u5206\u4f59\u989d\u548c\u793e\u4f1a\u5b89\u5168\u53f7\u7801","slug":"%e4%ba%bf%e7%94%b3%e8%af%b7%e4%bf%a1%e8%b4%b7%e7%9a%84%e4%ba%ba%e5%8f%97%e5%88%b0%e5%bd%b1%e5%93%8d%e9%bb%91%e5%ae%a2%e8%8e%b7%e5%be%97%e4%ba%86%e4%bf%a1%e7%94%a8%e8%af%84%e5%88%86%e4%bd%99%e9%a2%9d","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/tags\/3838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts?tags=3838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}