{"id":3809,"count":1,"description":"","link":"https:\/\/losangeleschinesenews.com\/index.php\/tag\/%e8%a7%84%e5%ae%9a\/","name":"\u89c4\u5b9a","slug":"%e8%a7%84%e5%ae%9a","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/tags\/3809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts?tags=3809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}