{"id":3768,"count":1,"description":"","link":"https:\/\/losangeleschinesenews.com\/index.php\/tag\/%e6%88%91%e5%9c%a8%e5%b7%a5%e4%bd%9c%e8%81%9a%e4%bc%9a%e4%b8%8a%e7%8a%af%e4%b8%8b%e7%9a%84%e5%b0%b4%e5%b0%ac%e7%9a%84%e9%92%b1%e5%8f%af%e4%bb%a5%e8%ae%a9%e4%bd%a0%e5%8f%98%e5%be%97%e6%9b%b4%e5%af%8c\/","name":"\u6211\u5728\u5de5\u4f5c\u805a\u4f1a\u4e0a\u72af\u4e0b\u7684\u5c34\u5c2c\u7684\u94b1\u53ef\u4ee5\u8ba9\u4f60\u53d8\u5f97\u66f4\u5bcc\u6709\u96f7\u5207\u5c14\u7406\u67e5\u5fb7\u65af\u7279\u52b3\u65af","slug":"%e6%88%91%e5%9c%a8%e5%b7%a5%e4%bd%9c%e8%81%9a%e4%bc%9a%e4%b8%8a%e7%8a%af%e4%b8%8b%e7%9a%84%e5%b0%b4%e5%b0%ac%e7%9a%84%e9%92%b1%e5%8f%af%e4%bb%a5%e8%ae%a9%e4%bd%a0%e5%8f%98%e5%be%97%e6%9b%b4%e5%af%8c","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/tags\/3768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts?tags=3768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}