{"id":3148,"date":"2026-07-15T18:58:01","date_gmt":"2026-07-15T10:58:01","guid":{"rendered":"https:\/\/losangeleschinesenews.com\/index.php\/2026\/07\/15\/%e5%8e%86%e5%8f%b2%e6%80%a7%e7%9a%84%e4%b8%96%e7%95%8c%e6%9d%af%e7%ab%9e%e4%ba%89%e9%87%8d%e6%96%b0%e7%87%83%e8%b5%b7%ef%bc%8c%e8%8b%b1%e6%a0%bc%e5%85%b0%e5%8f%af%e4%bb%a5%e9%a9%b1%e9%80%90%e9%98%bf\/"},"modified":"2026-07-15T18:58:01","modified_gmt":"2026-07-15T10:58:01","slug":"%e5%8e%86%e5%8f%b2%e6%80%a7%e7%9a%84%e4%b8%96%e7%95%8c%e6%9d%af%e7%ab%9e%e4%ba%89%e9%87%8d%e6%96%b0%e7%87%83%e8%b5%b7%ef%bc%8c%e8%8b%b1%e6%a0%bc%e5%85%b0%e5%8f%af%e4%bb%a5%e9%a9%b1%e9%80%90%e9%98%bf","status":"publish","type":"post","link":"https:\/\/losangeleschinesenews.com\/index.php\/2026\/07\/15\/%e5%8e%86%e5%8f%b2%e6%80%a7%e7%9a%84%e4%b8%96%e7%95%8c%e6%9d%af%e7%ab%9e%e4%ba%89%e9%87%8d%e6%96%b0%e7%87%83%e8%b5%b7%ef%bc%8c%e8%8b%b1%e6%a0%bc%e5%85%b0%e5%8f%af%e4%bb%a5%e9%a9%b1%e9%80%90%e9%98%bf\/","title":{"rendered":"\u5386\u53f2\u6027\u7684\u4e16\u754c\u676f\u7ade\u4e89\u91cd\u65b0\u71c3\u8d77\uff0c\u82f1\u683c\u5170\u53ef\u4ee5\u9a71\u9010\u963f\u6839\u5ef7\u6076\u9b54"},"content":{"rendered":"<p><\/p>\n<div>\n<p>\u963f\u6839\u5ef7\u961f\u5728\u4e16\u754c\u676f\u4e0a\u5df2\u521b\u7eaa\u5f55\u5730\u8fdb\u5165\u52a0\u65f6\u8d5b\u6216\u70b9\u7403\u5927\u6218 13 \u573a\uff0c\u8d62\u4e86 11 \u573a\uff0c\u5305\u62ec\u5468\u516d\u5728\u5bc6\u82cf\u91cc\u5dde\u582a\u8428\u65af\u57ce\u7684\u6bd4\u8d5b\uff0c\u5176\u4e2d\u4e00\u4e9b\u80dc\u5229\u662f\u7531\u65af\u5361\u7f57\u5c3c\u7684\u6559\u7ec3\u7ec4\u6210\u5458\u7ecf\u5386\u7684\uff0c\u5176\u4e2d\u5305\u62ec\u5df4\u52c3\u7f57\u00b7\u827e\u9a6c\u5c14\u3001\u6c83\u5c14\u7279\u00b7\u8428\u7f2a\u5c14\u3001\u963f\u6839\u5ef7\u5de8\u661f\u7f57\u4f2f\u6258\u00b7\u963f\u4e9a\u62c9\u3002<\/p>\n<\/div>\n<p>#\u5386\u53f2\u6027\u7684\u4e16\u754c\u676f\u7ade\u4e89\u91cd\u65b0\u71c3\u8d77\u82f1\u683c\u5170\u53ef\u4ee5\u9a71\u9010\u963f\u6839\u5ef7\u6076\u9b54<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u963f\u6839\u5ef7\u961f\u5728\u4e16\u754c\u676f\u4e0a\u5df2\u521b\u7eaa\u5f55\u5730\u8fdb\u5165\u52a0\u65f6\u8d5b\u6216\u70b9\u7403\u5927\u6218 13 \u573a\uff0c&hellip; <\/p>\n","protected":false},"author":1,"featured_media":3149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[3864,584,585],"class_list":["post-3148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-16","tag-3864","tag-584","tag-585"],"_links":{"self":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts\/3148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/comments?post=3148"}],"version-history":[{"count":0,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts\/3148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/media\/3149"}],"wp:attachment":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/media?parent=3148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/categories?post=3148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/tags?post=3148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}