{"id":3138,"date":"2026-07-15T17:04:37","date_gmt":"2026-07-15T09:04:37","guid":{"rendered":"https:\/\/losangeleschinesenews.com\/index.php\/2026\/07\/15\/%e9%85%8d%e5%a4%87%e6%89%8b%e5%86%99%e7%ac%94%e7%9a%84-galaxy-tab-s10-lite-%e5%9c%a8%e6%b2%83%e5%b0%94%e7%8e%9b%e5%94%ae%e4%bb%b7-299-%e7%be%8e%e5%85%83\/"},"modified":"2026-07-15T17:04:37","modified_gmt":"2026-07-15T09:04:37","slug":"%e9%85%8d%e5%a4%87%e6%89%8b%e5%86%99%e7%ac%94%e7%9a%84-galaxy-tab-s10-lite-%e5%9c%a8%e6%b2%83%e5%b0%94%e7%8e%9b%e5%94%ae%e4%bb%b7-299-%e7%be%8e%e5%85%83","status":"publish","type":"post","link":"https:\/\/losangeleschinesenews.com\/index.php\/2026\/07\/15\/%e9%85%8d%e5%a4%87%e6%89%8b%e5%86%99%e7%ac%94%e7%9a%84-galaxy-tab-s10-lite-%e5%9c%a8%e6%b2%83%e5%b0%94%e7%8e%9b%e5%94%ae%e4%bb%b7-299-%e7%be%8e%e5%85%83\/","title":{"rendered":"\u914d\u5907\u624b\u5199\u7b14\u7684 Galaxy Tab S10 Lite \u5728\u6c83\u5c14\u739b\u552e\u4ef7 299 \u7f8e\u5143"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/m-cdn.phonearena.com\/images\/article\/181863-two\/Stylus-powered-Galaxy-Tab-S10-Lite-becomes-a-299-steal-at-Walmart.jpg\" \/><br \/>\u8d81\u4f18\u60e0\u6301\u7eed\uff0c\u8d76\u5feb\u884c\u52a8\uff0c\u7701\u94b1\u5427\uff01<br \/>\n<br \/>#\u914d\u5907\u624b\u5199\u7b14\u7684 #Galaxy #Tab #S10 #Lite #\u5728\u6c83\u5c14\u739b\u552e\u4ef7 #\u7f8e\u5143<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u8d81\u4f18\u60e0\u6301\u7eed\uff0c\u8d76\u5feb\u884c\u52a8\uff0c\u7701\u94b1\u5427\uff01 #\u914d\u5907\u624b\u5199\u7b14\u7684 #Galax&hellip; <\/p>\n","protected":false},"author":1,"featured_media":3139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[215],"tags":[329,868,646,645,3855,481,3854],"class_list":["post-3138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-215","tag-galaxy","tag-lite","tag-s10","tag-tab","tag-3855","tag-481","tag-3854"],"_links":{"self":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts\/3138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/comments?post=3138"}],"version-history":[{"count":0,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts\/3138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/media\/3139"}],"wp:attachment":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/media?parent=3138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/categories?post=3138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/tags?post=3138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}