{"id":3126,"date":"2026-07-15T15:59:31","date_gmt":"2026-07-15T07:59:31","guid":{"rendered":"https:\/\/losangeleschinesenews.com\/index.php\/2026\/07\/15\/2019-%e5%b9%b4%e7%ac%ac%e4%b8%80%e8%b5%84%e6%9c%ac%e6%95%b0%e6%8d%ae%e6%b3%84%e9%9c%b2%ef%bc%9a%e8%b6%85%e8%bf%87-1-%e4%ba%bf%e7%94%b3%e8%af%b7%e4%bf%a1%e8%b4%b7%e7%9a%84%e4%ba%ba%e5%8f%97%e5%88%b0\/"},"modified":"2026-07-15T15:59:31","modified_gmt":"2026-07-15T07:59:31","slug":"2019-%e5%b9%b4%e7%ac%ac%e4%b8%80%e8%b5%84%e6%9c%ac%e6%95%b0%e6%8d%ae%e6%b3%84%e9%9c%b2%ef%bc%9a%e8%b6%85%e8%bf%87-1-%e4%ba%bf%e7%94%b3%e8%af%b7%e4%bf%a1%e8%b4%b7%e7%9a%84%e4%ba%ba%e5%8f%97%e5%88%b0","status":"publish","type":"post","link":"https:\/\/losangeleschinesenews.com\/index.php\/2026\/07\/15\/2019-%e5%b9%b4%e7%ac%ac%e4%b8%80%e8%b5%84%e6%9c%ac%e6%95%b0%e6%8d%ae%e6%b3%84%e9%9c%b2%ef%bc%9a%e8%b6%85%e8%bf%87-1-%e4%ba%bf%e7%94%b3%e8%af%b7%e4%bf%a1%e8%b4%b7%e7%9a%84%e4%ba%ba%e5%8f%97%e5%88%b0\/","title":{"rendered":"2019 \u5e74\u7b2c\u4e00\u8d44\u672c\u6570\u636e\u6cc4\u9732\uff1a\u8d85\u8fc7 1 \u4ebf\u7533\u8bf7\u4fe1\u8d37\u7684\u4eba\u53d7\u5230\u5f71\u54cd\uff0c\u9ed1\u5ba2\u83b7\u5f97\u4e86\u4fe1\u7528\u8bc4\u5206\u3001\u4f59\u989d\u548c\u793e\u4f1a\u5b89\u5168\u53f7\u7801"},"content":{"rendered":"<p><\/p>\n<div id=\"article-0\">\n  <!-- lil observer --><br \/>\n      <span class=\"content__observer-marker content__observer-marker--fixed lazyload\"\/><\/p>\n<section class=\"content__body\">\n<p>Capital One \u8868\u793a\uff0c\u4e00\u540d\u9ed1\u5ba2\u83b7\u53d6\u4e86\u8d85\u8fc7 1 \u4ebf\u7533\u8bf7\u4fe1\u8d37\u7684\u4e2a\u4eba\u4fe1\u606f\u3002\u8fd9\u5bb6\u603b\u90e8\u4f4d\u4e8e\u5f17\u5409\u5c3c\u4e9a\u5dde\u9ea6\u514b\u83b1\u6069\u7684\u94f6\u884c\u5468\u4e00\u8868\u793a\uff0c\u5b83\u4e8e 7 \u6708 19 \u65e5\u53d1\u73b0\u5176\u7cfb\u7edf\u5b58\u5728\u6f0f\u6d1e\uff0c\u5e76\u7acb\u5373\u5411\u6267\u6cd5\u90e8\u95e8\u5bfb\u6c42\u5e2e\u52a9\u4ee5\u6293\u83b7\u8087\u4e8b\u8005\u3002<\/p>\n<p>\u636e\u300a\u534e\u76db\u987f\u90ae\u62a5\u300b\u62a5\u9053\uff0c\u8054\u90a6\u8c03\u67e5\u5c40\u5df2\u5728\u897f\u96c5\u56fe\u902e\u6355\u4e86\u6b64\u4eba\u3002\u636e CNET \u62a5\u9053\uff0c\u6cd5\u5ead\u8bb0\u5f55\u663e\u793a\uff0c\u5468\u4e00\uff0c\u4e00\u540d\u540d\u53eb\u4f69\u5947\u00b7A\u00b7\u6c64\u666e\u68ee (Paige A. Thompson) \u7684\u5987\u5973\u56e0\u8ba1\u7b97\u673a\u6b3a\u8bc8\u548c\u8650\u5f85\u7f6a\u88ab\u6355\u3002\u68c0\u5bdf\u5b98\u79f0\uff0c\u9ed1\u5ba2\u653b\u51fb\u53d1\u751f\u5728 3 \u6708 12 \u65e5\u81f3 7 \u6708 17 \u65e5\u671f\u95f4\u3002<\/p>\n<p>\u7b2c\u4e00\u8d44\u672c\u8868\u793a\uff0c\u8ba4\u4e3a\u8be5\u4fe1\u606f\u4e0d\u592a\u53ef\u80fd\u88ab\u7528\u4e8e\u6b3a\u8bc8\uff0c\u4f46\u4f1a\u7ee7\u7eed\u8c03\u67e5\u3002<\/p>\n<p>\u7b2c\u4e00\u8d44\u672c\u8463\u4e8b\u957f\u517c\u9996\u5e2d\u6267\u884c\u5b98\u7406\u67e5\u5fb7\u00b7\u8d39\u5c14\u73ed\u514b (Richard D. Fairbank) \u5728\u4e00\u4efd\u65b0\u95fb\u7a3f\u4e2d\u8868\u793a\uff1a\u201c\u867d\u7136\u6211\u5f88\u5e86\u5e78\u8087\u4e8b\u8005\u5df2\u88ab\u6293\u83b7\uff0c\u4f46\u6211\u5bf9\u6240\u53d1\u751f\u7684\u4e8b\u60c5\u6df1\u8868\u9057\u61be\u3002\u201d \u201c\u5bf9\u4e8e\u8fd9\u4e00\u4e8b\u4ef6\u7ed9\u53d7\u5f71\u54cd\u7684\u4eba\u4eec\u5e26\u6765\u7684\u62c5\u5fe7\uff0c\u6211\u771f\u8bda\u5730\u9053\u6b49\uff0c\u8fd9\u662f\u53ef\u4ee5\u7406\u89e3\u7684\uff0c\u6211\u81f4\u529b\u4e8e\u7ea0\u6b63\u8fd9\u79cd\u60c5\u51b5\u3002\u201d<\/p>\n<figure class=\"embed embed--type-video embed--type-content_video is-video embed--float-none embed--size-medium\"><figcaption class=\"embed__caption-container\">\n<p>          <span class=\"embed__icon\"><br \/>\n            <svg viewbox=\"0 0 32 32\" aria-hidden=\"true\">\n              <use xlink:href=\"#icon-video\"\/>\n            <\/svg><br \/>\n          <\/span><\/p>\n<p>          <span class=\"embed__headline\">Capital One \u6570\u636e\u6cc4\u9732\u5f71\u54cd\u8d85\u8fc7 1 \u4ebf\u5ba2\u6237<\/span><\/p>\n<p>          <span class=\"embed__video-duration\">09:38<\/span><\/p>\n<\/figcaption><\/figure>\n<p>\u9ed1\u5ba2\u83b7\u5f97\u4e86\u5927\u7ea6 140,000 \u540d\u5ba2\u6237\u7684\u4fe1\u606f\uff0c\u5305\u62ec\u4fe1\u7528\u8bc4\u5206\u548c\u4f59\u989d\u4ee5\u53ca\u793e\u4f1a\u5b89\u5168\u53f7\u7801\u3002\u5b83\u5c06\u5411\u53d7\u5f71\u54cd\u7684\u4eba\u63d0\u4f9b\u514d\u8d39\u7684\u4fe1\u7528\u76d1\u63a7\u670d\u52a1\u3002<\/p>\n<p>\u6b64\u6b21\u6570\u636e\u6cc4\u9732\u5f71\u54cd\u4e86\u7f8e\u56fd\u7ea6 1 \u4ebf\u4eba\u548c\u52a0\u62ff\u5927 600 \u4e07\u4eba\u3002<\/p>\n<p>\u636e\u53f8\u6cd5\u90e8\u79f0\uff0c\u8ba1\u7b97\u673a\u6b3a\u8bc8\u548c\u6ee5\u7528\u6700\u9ad8\u53ef\u5224\u5904\u4e94\u5e74\u76d1\u7981\u548c 25 \u4e07\u7f8e\u5143\u7f5a\u6b3e\u3002<\/p>\n<p>\u636e CNET \u62a5\u9053\uff0cEquifax \u53ef\u80fd\u9700\u8981\u4e3a 2017 \u5e74\u6570\u636e\u6cc4\u9732\u4e8b\u4ef6\u652f\u4ed8\u9ad8\u8fbe 7 \u4ebf\u7f8e\u5143\u7684\u8d54\u507f\u91d1\uff0c\u5728\u6b64\u4e4b\u540e\u53d1\u5e03\u4e86\u8fd9\u4efd\u62a5\u544a\u3002 2017 \u5e74 5 \u6708\u81f3 7 \u6708\u53d1\u751f\u7684\u4e00\u6b21\u9ed1\u5ba2\u653b\u51fb\u4e2d\uff0cEquifax \u670d\u52a1\u5668\u4e0a\u8fd1 1.48 \u4ebf\u7f8e\u56fd\u4eba\u7684\u793e\u4f1a\u5b89\u5168\u53f7\u7801\u548c\u5bb6\u5ead\u5730\u5740\u906d\u5230\u6cc4\u9732\u3002<\/p>\n<section class=\"content__body--footer\">\n<\/section>\n<p>  <!-- data-recirc-source=\"chartbeat\" --><\/p>\n<aside class=\"component list recirculation component--type-recirculation  component--type-recirculation-collection\">\n<div class=\"component__heading-wrapper recirc\">\n<h3 class=\"component__title\">\u6280\u672f\u5b89\u5168\u4e0e\u9690\u79c1 \u66f4\u591a<br \/>\n                <svg viewbox=\"0 0 32 32\" class=\"icon__caret-right\" aria-hidden=\"true\">\n                  <use xlink:href=\"#icon-caret-down\"\/>\n                <\/svg><\/p>\n<\/h3><\/div>\n<div class=\"component__item-recirc-block\">\n<p><h3 class=\"component__title\">\u4e0e\u81ea\u7531\u65b0\u95fb\u4e00\u8d77\u6df1\u5165\u4e86\u89e3<\/h3>\n<\/p><\/div>\n<\/aside>\n<section class=\"content__body--footer\">\n      <!-- tags --><\/p>\n<section class=\"content__tags\">\n<p class=\"content__tags__label\">\u5728\uff1a<\/p>\n<\/section>\n<\/section>\n<\/section>\n<\/div>\n<p>#\u5e74\u7b2c\u4e00\u8d44\u672c\u6570\u636e\u6cc4\u9732\u8d85\u8fc7 #\u4ebf\u7533\u8bf7\u4fe1\u8d37\u7684\u4eba\u53d7\u5230\u5f71\u54cd\u9ed1\u5ba2\u83b7\u5f97\u4e86\u4fe1\u7528\u8bc4\u5206\u4f59\u989d\u548c\u793e\u4f1a\u5b89\u5168\u53f7\u7801<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capital One \u8868\u793a\uff0c\u4e00\u540d\u9ed1\u5ba2\u83b7\u53d6\u4e86\u8d85\u8fc7 1 \u4ebf\u7533\u8bf7&hellip; <\/p>\n","protected":false},"author":1,"featured_media":3127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[216],"tags":[3838,3837,3836,3821,3820,1805],"class_list":["post-3126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-216","tag-3838","tag-3837","tag-3836","tag-3821","tag-3820","tag-1805"],"_links":{"self":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts\/3126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/comments?post=3126"}],"version-history":[{"count":0,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/posts\/3126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/media\/3127"}],"wp:attachment":[{"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/media?parent=3126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/categories?post=3126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losangeleschinesenews.com\/index.php\/wp-json\/wp\/v2\/tags?post=3126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}